{"id":3192,"date":"2016-11-28T23:31:02","date_gmt":"2016-11-29T04:31:02","guid":{"rendered":"https:\/\/www.conformit.com\/non-classifiee\/labc-des-normes-sse-en-amerique-du-nord\/"},"modified":"2023-05-30T13:47:47","modified_gmt":"2023-05-30T17:47:47","slug":"labc-des-normes-sse-en-amerique-du-nord","status":"publish","type":"post","link":"https:\/\/www.conformit.com\/fr\/modes-demploi\/labc-des-normes-sse-en-amerique-du-nord\/","title":{"rendered":"L&rsquo;ABC des normes SSE en Am\u00e9rique du Nord"},"content":{"rendered":"<h1>Normes SSE en Am\u00e9rique du Nord<\/h1>\n<p style=\"text-align: justify;\">La mission des organismes de normalisation est, au sens tr\u00e8s large, d\u2019offrir les solutions dont les fabricants, les d\u00e9taillants, les pouvoirs de r\u00e9glementation et les consommateurs ont besoin pour fonctionner en toute s\u00e9curit\u00e9 dans notre monde d\u2019aujourd\u2019hui en constante \u00e9volution. Les domaines couverts sont nombreux. Chez CSA, par exemple, on retrouve les \u00e9quipements m\u00e9caniques et industriels, la construction et l\u2019ing\u00e9nierie, les technologies de l\u2019information et les t\u00e9l\u00e9communications, les infrastructures et les travaux publics, l\u2019\u00e9lectricit\u00e9, l\u2019\u00e9nergie, la s\u00e9curit\u00e9 et le bien-\u00eatre communautaires, les soins de sant\u00e9, les syst\u00e8mes de gestion de la production, l\u2019environnement et la sant\u00e9 et s\u00e9curit\u00e9 au travail.<\/p>\n<p style=\"text-align: justify;\">Les produits d\u00e9velopp\u00e9s sont principalement des normes et des outils de mise en \u0153uvre comme des guides et des lignes directrices. Ils viennent compl\u00e9ter les lois et les r\u00e8glements \u00e9labor\u00e9s par les diff\u00e9rentes juridictions en Am\u00e9rique du Nord.<\/p>\n<p style=\"text-align: justify;\">De plus, dans la plupart des juridictions particuli\u00e8res aussi bien qu\u2019au niveau international, les normes vont de domaines d\u2019application tr\u00e8s large \u00e0 tr\u00e8s pr\u00e9cis : syst\u00e8mes de gestion, programmes, cat\u00e9gories d\u2019\u00e9l\u00e9ments, machines jusqu\u2019\u00e0 pi\u00e8ces d\u2019\u00e9quipement. Les normes touchant la sant\u00e9 et la s\u00e9curit\u00e9 au travail et l\u2019environnement n\u2019\u00e9chappent pas \u00e0 cette r\u00e8gle.<\/p>\n<h2 style=\"text-align: left;\">Syst\u00e8mes de gestion<\/h2>\n<p style=\"text-align: justify;\">La norme utilis\u00e9e en Am\u00e9rique du Nord pour les syst\u00e8mes de management environnemental est la norme ISO 14001. Les principes d\u2019am\u00e9lioration continue bas\u00e9s sur le processus Planifier-Mettre en oeuvre-V\u00e9rifier-Agir (Plan-Do-Check-Act) sont pr\u00e9conis\u00e9s partout. Au Canada, la norme CAN\/CSA ISO 14001-2004 a \u00e9t\u00e9 publi\u00e9e en 2004 et confirm\u00e9e en 2014.<\/p>\n<p style=\"text-align: justify;\">En ce qui concerne les syst\u00e8mes de gestion de la sant\u00e9 et de la s\u00e9curit\u00e9 au travail (SGSST), le Canada et les USA poss\u00e8dent leur propre norme, la CSA Z1001-14 et la ANSI\/AIHA\/ASSE Z10-2012 respectivement. Ces normes reposent \u00e9galement sur le m\u00eame processus d\u2019am\u00e9lioration continue que la norme ISO 14001. Il est \u00e0 noter que la norme ISO 45001, portant sur ce sujet, est en cours de d\u00e9veloppement.<\/p>\n<h2 style=\"text-align: left;\">Programmes<\/h2>\n<p style=\"text-align: justify;\">Comme le pr\u00e9conisent les normes sur les syst\u00e8mes de gestion, \u00e0 partir de l\u2019identification des ph\u00e9nom\u00e8nes dangereux et de l\u2019appr\u00e9ciation des risques, chaque organisation devra mettre en \u0153uvre des programmes pour \u00e9liminer ces ph\u00e9nom\u00e8nes dangereux ou, \u00e0 d\u00e9faut de les \u00e9liminer compl\u00e8tement, d\u2019en r\u00e9duire les risques \u00e0 un niveau acceptable.<\/p>\n<p style=\"text-align: justify;\">Ces programmes d\u00e9finiront les ressources n\u00e9cessaires de m\u00eame que les r\u00f4les, les responsabilit\u00e9s et l\u2019autorit\u00e9 qui seront attribu\u00e9s \u00e0 chaque intervenant. Les programmes incluront aussi les comp\u00e9tences \u00e0 d\u00e9velopper, la formation, la sensibilisation et la communication requises, les r\u00e8gles de ma\u00eetrise documentaire et op\u00e9rationnelle et les mesures d\u2019urgence.<\/p>\n<p style=\"text-align: justify;\">Un syst\u00e8me de surveillance et d\u2019\u00e9valuation de la conformit\u00e9 devra \u00eatre mis en place pour permettre les revues de direction et l\u2019am\u00e9lioration des programmes sur une base continue.<\/p>\n<p style=\"text-align: justify;\">Plusieurs normes couvrent l\u2019\u00e9laboration des programmes dans diff\u00e9rents domaines : entr\u00e9e en espace clos (ANSI Z117 et CSA Z1006), ma\u00eetrise des \u00e9nergies dangereuses (ANSI Z244 et CSA Z460), s\u00e9curit\u00e9 \u00e9lectrique en milieu de travail (NFPA 70E et CSA Z462), entre autres. Chaque juridiction poss\u00e8de aussi des r\u00e8gles de protection environnementale touchant plusieurs th\u00e8mes souvent inspir\u00e9s des normes internationales comme l\u2019empreinte eau (ISO 14046) et la gestion des gaz \u00e0 effet de serre (ISO 14064).<\/p>\n<p style=\"text-align: justify;\">L\u2019hygi\u00e8ne industrielle vise \u00e0 assurer la qualit\u00e9 du milieu de travail en contr\u00f4lant les agents agresseurs qui peuvent avoir un impact sur la sant\u00e9 des travailleurs. Ce domaine doit \u00eatre int\u00e9grer dans le syst\u00e8me de gestion tout comme la s\u00e9curit\u00e9 l\u2019est.<\/p>\n<h2 style=\"text-align: left;\">Technologies<\/h2>\n<p style=\"text-align: justify;\">Une fois les programmes en place, une panoplie de normes est disponible pour supporter l\u2019utilisation de technologies particuli\u00e8res mises en \u0153uvre \u00e0 partir des programmes pour \u00e9liminer ou r\u00e9duire le risque. Ces normes touchent, par exemple, la s\u00e9curit\u00e9 des machines dans son ensemble (ANSI B11.0 et CSA Z432) ou des cat\u00e9gories de machine sp\u00e9cifiques comme les robots (ANSI\/RIA R15.06 et CSA Z434) et les presses (ANSI B11.1 et CSA Z142).<\/p>\n<p style=\"text-align: justify;\">L\u2019ensemble des domaines touch\u00e9s par des normes sp\u00e9cifiques \u00e0 des technologies est tr\u00e8s vaste. Ainsi, l\u2019ASTM (American Society for Testing and Materials) et l\u2019AIHA (American Industrial Hygiene Association) ont \u00e9labor\u00e9 des normes et des guides concernant l\u2019hygi\u00e8ne industrielle. Les \u00e9quipements de protection individuelle sont \u00e9galement l\u2019objet de normes qu\u2019il s\u2019agisse des casques, des gants ou des harnais.<\/p>\n<h2 style=\"text-align: left;\">Ce qu\u2019il faut retenir<\/h2>\n<p style=\"text-align: justify;\">Les diff\u00e9rentes juridictions en Am\u00e9rique du nord se sont dot\u00e9es d\u2019un syst\u00e8me de normes pour am\u00e9liorer nos soci\u00e9t\u00e9s sur les plans technique, \u00e9conomique et soci\u00e9tal. Les normes relatives \u00e0 la sant\u00e9, \u00e0 la s\u00e9curit\u00e9 et \u00e0 l\u2019environnement contribue largement \u00e0 l\u2019atteinte de cet objectif et sont des outils strat\u00e9giques permettant aux entreprises de relever les d\u00e9fis de l\u2019\u00e9conomie moderne. Elles contribuent \u00e0 diminuer les co\u00fbts et \u00e0 assurer les responsabilit\u00e9s soci\u00e9tales des entreprises tout en leur permettant d\u2019augmenter leurs parts de march\u00e9 et de r\u00e9duire leurs impacts n\u00e9gatifs sur l\u2019environnement.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Normes SSE en Am\u00e9rique du Nord La mission des organismes de normalisation est, au sens tr\u00e8s large, d\u2019offrir les solutions dont les fabricants, les d\u00e9taillants, les pouvoirs de r\u00e9glementation et [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":5205,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[62],"tags":[],"class_list":["post-3192","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-modes-demploi"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;ABC des normes SSE en Am\u00e9rique du Nord - CONFORMiT<\/title>\n<meta name=\"description\" content=\"Informations SSE dont on a besoin pour fonctionner en toute s\u00e9curit\u00e9 dans notre monde d\u2019aujourd\u2019hui en constante \u00e9volution.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.conformit.com\/fr\/modes-demploi\/labc-des-normes-sse-en-amerique-du-nord\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;ABC des normes SSE en Am\u00e9rique du Nord - CONFORMiT\" \/>\n<meta property=\"og:description\" content=\"Informations SSE dont on a besoin pour fonctionner en toute s\u00e9curit\u00e9 dans notre monde d\u2019aujourd\u2019hui en constante \u00e9volution.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.conformit.com\/fr\/modes-demploi\/labc-des-normes-sse-en-amerique-du-nord\/\" \/>\n<meta property=\"og:site_name\" content=\"CONFORMiT\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/conformit\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-29T04:31:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-30T17:47:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.conformit.com\/wp-content\/uploads\/2021\/12\/jackson-jost-J-LMPtk8tmg-unsplash-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Maxime Ouellet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@conformit_ehs\" \/>\n<meta name=\"twitter:site\" content=\"@conformit_ehs\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maxime Ouellet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.conformit.com\\\/fr\\\/modes-demploi\\\/labc-des-normes-sse-en-amerique-du-nord\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.conformit.com\\\/fr\\\/modes-demploi\\\/labc-des-normes-sse-en-amerique-du-nord\\\/\"},\"author\":{\"name\":\"Maxime Ouellet\",\"@id\":\"https:\\\/\\\/www.conformit.com\\\/fr\\\/#\\\/schema\\\/person\\\/45776106c96e7224c0362fc64d99d2b7\"},\"headline\":\"L&rsquo;ABC des normes SSE en Am\u00e9rique du Nord\",\"datePublished\":\"2016-11-29T04:31:02+00:00\",\"dateModified\":\"2023-05-30T17:47:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.conformit.com\\\/fr\\\/modes-demploi\\\/labc-des-normes-sse-en-amerique-du-nord\\\/\"},\"wordCount\":919,\"publisher\":{\"@id\":\"https:\\\/\\\/www.conformit.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.conformit.com\\\/fr\\\/modes-demploi\\\/labc-des-normes-sse-en-amerique-du-nord\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.conformit.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/jackson-jost-J-LMPtk8tmg-unsplash-scaled.jpg\",\"articleSection\":[\"Modes d'emploi\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.conformit.com\\\/fr\\\/modes-demploi\\\/labc-des-normes-sse-en-amerique-du-nord\\\/\",\"url\":\"https:\\\/\\\/www.conformit.com\\\/fr\\\/modes-demploi\\\/labc-des-normes-sse-en-amerique-du-nord\\\/\",\"name\":\"L'ABC des normes SSE en Am\u00e9rique du Nord - CONFORMiT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.conformit.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.conformit.com\\\/fr\\\/modes-demploi\\\/labc-des-normes-sse-en-amerique-du-nord\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.conformit.com\\\/fr\\\/modes-demploi\\\/labc-des-normes-sse-en-amerique-du-nord\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.conformit.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/jackson-jost-J-LMPtk8tmg-unsplash-scaled.jpg\",\"datePublished\":\"2016-11-29T04:31:02+00:00\",\"dateModified\":\"2023-05-30T17:47:47+00:00\",\"description\":\"Informations SSE dont on a besoin pour fonctionner en toute s\u00e9curit\u00e9 dans notre monde d\u2019aujourd\u2019hui en constante \u00e9volution.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.conformit.com\\\/fr\\\/modes-demploi\\\/labc-des-normes-sse-en-amerique-du-nord\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.conformit.com\\\/fr\\\/modes-demploi\\\/labc-des-normes-sse-en-amerique-du-nord\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.conformit.com\\\/fr\\\/modes-demploi\\\/labc-des-normes-sse-en-amerique-du-nord\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.conformit.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/jackson-jost-J-LMPtk8tmg-unsplash-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.conformit.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/jackson-jost-J-LMPtk8tmg-unsplash-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"EHS_standard_safety_software_conformit\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.conformit.com\\\/fr\\\/modes-demploi\\\/labc-des-normes-sse-en-amerique-du-nord\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.conformit.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&rsquo;ABC des normes SSE en Am\u00e9rique du Nord\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.conformit.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.conformit.com\\\/fr\\\/\",\"name\":\"CONFORMiT: EHS Management Software\",\"description\":\"Le logiciel SST le plus intuitif sur le march\u00e9\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.conformit.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.conformit.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.conformit.com\\\/fr\\\/#organization\",\"name\":\"CONFORMiT: EHS Management Software\",\"url\":\"https:\\\/\\\/www.conformit.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.conformit.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.conformit.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logo-cit2-3.png\",\"contentUrl\":\"https:\\\/\\\/www.conformit.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logo-cit2-3.png\",\"width\":1000,\"height\":300,\"caption\":\"CONFORMiT: EHS Management Software\"},\"image\":{\"@id\":\"https:\\\/\\\/www.conformit.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/conformit\",\"https:\\\/\\\/x.com\\\/conformit_ehs\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/conformit\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@CONFORMiT\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.conformit.com\\\/fr\\\/#\\\/schema\\\/person\\\/45776106c96e7224c0362fc64d99d2b7\",\"name\":\"Maxime Ouellet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f21ba64d1c1a20c59d7b9f681cc659723fe0be7663038c7fcad7c08d1862db94?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f21ba64d1c1a20c59d7b9f681cc659723fe0be7663038c7fcad7c08d1862db94?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f21ba64d1c1a20c59d7b9f681cc659723fe0be7663038c7fcad7c08d1862db94?s=96&d=mm&r=g\",\"caption\":\"Maxime Ouellet\"},\"url\":\"https:\\\/\\\/www.conformit.com\\\/fr\\\/author\\\/maxime_ouellet\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'ABC des normes SSE en Am\u00e9rique du Nord - CONFORMiT","description":"Informations SSE dont on a besoin pour fonctionner en toute s\u00e9curit\u00e9 dans notre monde d\u2019aujourd\u2019hui en constante \u00e9volution.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.conformit.com\/fr\/modes-demploi\/labc-des-normes-sse-en-amerique-du-nord\/","og_locale":"fr_FR","og_type":"article","og_title":"L'ABC des normes SSE en Am\u00e9rique du Nord - CONFORMiT","og_description":"Informations SSE dont on a besoin pour fonctionner en toute s\u00e9curit\u00e9 dans notre monde d\u2019aujourd\u2019hui en constante \u00e9volution.","og_url":"https:\/\/www.conformit.com\/fr\/modes-demploi\/labc-des-normes-sse-en-amerique-du-nord\/","og_site_name":"CONFORMiT","article_publisher":"https:\/\/www.facebook.com\/conformit","article_published_time":"2016-11-29T04:31:02+00:00","article_modified_time":"2023-05-30T17:47:47+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.conformit.com\/wp-content\/uploads\/2021\/12\/jackson-jost-J-LMPtk8tmg-unsplash-scaled.jpg","type":"image\/jpeg"}],"author":"Maxime Ouellet","twitter_card":"summary_large_image","twitter_creator":"@conformit_ehs","twitter_site":"@conformit_ehs","twitter_misc":{"\u00c9crit par":"Maxime Ouellet","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.conformit.com\/fr\/modes-demploi\/labc-des-normes-sse-en-amerique-du-nord\/#article","isPartOf":{"@id":"https:\/\/www.conformit.com\/fr\/modes-demploi\/labc-des-normes-sse-en-amerique-du-nord\/"},"author":{"name":"Maxime Ouellet","@id":"https:\/\/www.conformit.com\/fr\/#\/schema\/person\/45776106c96e7224c0362fc64d99d2b7"},"headline":"L&rsquo;ABC des normes SSE en Am\u00e9rique du Nord","datePublished":"2016-11-29T04:31:02+00:00","dateModified":"2023-05-30T17:47:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.conformit.com\/fr\/modes-demploi\/labc-des-normes-sse-en-amerique-du-nord\/"},"wordCount":919,"publisher":{"@id":"https:\/\/www.conformit.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.conformit.com\/fr\/modes-demploi\/labc-des-normes-sse-en-amerique-du-nord\/#primaryimage"},"thumbnailUrl":"https:\/\/www.conformit.com\/wp-content\/uploads\/2021\/12\/jackson-jost-J-LMPtk8tmg-unsplash-scaled.jpg","articleSection":["Modes d'emploi"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.conformit.com\/fr\/modes-demploi\/labc-des-normes-sse-en-amerique-du-nord\/","url":"https:\/\/www.conformit.com\/fr\/modes-demploi\/labc-des-normes-sse-en-amerique-du-nord\/","name":"L'ABC des normes SSE en Am\u00e9rique du Nord - CONFORMiT","isPartOf":{"@id":"https:\/\/www.conformit.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.conformit.com\/fr\/modes-demploi\/labc-des-normes-sse-en-amerique-du-nord\/#primaryimage"},"image":{"@id":"https:\/\/www.conformit.com\/fr\/modes-demploi\/labc-des-normes-sse-en-amerique-du-nord\/#primaryimage"},"thumbnailUrl":"https:\/\/www.conformit.com\/wp-content\/uploads\/2021\/12\/jackson-jost-J-LMPtk8tmg-unsplash-scaled.jpg","datePublished":"2016-11-29T04:31:02+00:00","dateModified":"2023-05-30T17:47:47+00:00","description":"Informations SSE dont on a besoin pour fonctionner en toute s\u00e9curit\u00e9 dans notre monde d\u2019aujourd\u2019hui en constante \u00e9volution.","breadcrumb":{"@id":"https:\/\/www.conformit.com\/fr\/modes-demploi\/labc-des-normes-sse-en-amerique-du-nord\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.conformit.com\/fr\/modes-demploi\/labc-des-normes-sse-en-amerique-du-nord\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.conformit.com\/fr\/modes-demploi\/labc-des-normes-sse-en-amerique-du-nord\/#primaryimage","url":"https:\/\/www.conformit.com\/wp-content\/uploads\/2021\/12\/jackson-jost-J-LMPtk8tmg-unsplash-scaled.jpg","contentUrl":"https:\/\/www.conformit.com\/wp-content\/uploads\/2021\/12\/jackson-jost-J-LMPtk8tmg-unsplash-scaled.jpg","width":2560,"height":1707,"caption":"EHS_standard_safety_software_conformit"},{"@type":"BreadcrumbList","@id":"https:\/\/www.conformit.com\/fr\/modes-demploi\/labc-des-normes-sse-en-amerique-du-nord\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.conformit.com\/fr\/"},{"@type":"ListItem","position":2,"name":"L&rsquo;ABC des normes SSE en Am\u00e9rique du Nord"}]},{"@type":"WebSite","@id":"https:\/\/www.conformit.com\/fr\/#website","url":"https:\/\/www.conformit.com\/fr\/","name":"CONFORMiT: EHS Management Software","description":"Le logiciel SST le plus intuitif sur le march\u00e9","publisher":{"@id":"https:\/\/www.conformit.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.conformit.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.conformit.com\/fr\/#organization","name":"CONFORMiT: EHS Management Software","url":"https:\/\/www.conformit.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.conformit.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.conformit.com\/wp-content\/uploads\/2023\/05\/logo-cit2-3.png","contentUrl":"https:\/\/www.conformit.com\/wp-content\/uploads\/2023\/05\/logo-cit2-3.png","width":1000,"height":300,"caption":"CONFORMiT: EHS Management Software"},"image":{"@id":"https:\/\/www.conformit.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/conformit","https:\/\/x.com\/conformit_ehs","https:\/\/www.linkedin.com\/company\/conformit\/","https:\/\/www.youtube.com\/@CONFORMiT"]},{"@type":"Person","@id":"https:\/\/www.conformit.com\/fr\/#\/schema\/person\/45776106c96e7224c0362fc64d99d2b7","name":"Maxime Ouellet","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/f21ba64d1c1a20c59d7b9f681cc659723fe0be7663038c7fcad7c08d1862db94?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f21ba64d1c1a20c59d7b9f681cc659723fe0be7663038c7fcad7c08d1862db94?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f21ba64d1c1a20c59d7b9f681cc659723fe0be7663038c7fcad7c08d1862db94?s=96&d=mm&r=g","caption":"Maxime Ouellet"},"url":"https:\/\/www.conformit.com\/fr\/author\/maxime_ouellet\/"}]}},"_links":{"self":[{"href":"https:\/\/www.conformit.com\/fr\/wp-json\/wp\/v2\/posts\/3192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.conformit.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.conformit.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.conformit.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.conformit.com\/fr\/wp-json\/wp\/v2\/comments?post=3192"}],"version-history":[{"count":2,"href":"https:\/\/www.conformit.com\/fr\/wp-json\/wp\/v2\/posts\/3192\/revisions"}],"predecessor-version":[{"id":4858,"href":"https:\/\/www.conformit.com\/fr\/wp-json\/wp\/v2\/posts\/3192\/revisions\/4858"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.conformit.com\/fr\/wp-json\/wp\/v2\/media\/5205"}],"wp:attachment":[{"href":"https:\/\/www.conformit.com\/fr\/wp-json\/wp\/v2\/media?parent=3192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.conformit.com\/fr\/wp-json\/wp\/v2\/categories?post=3192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.conformit.com\/fr\/wp-json\/wp\/v2\/tags?post=3192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}